{"id":42,"count":1,"description":"","link":"https:\/\/topbrandingaltimeter.com\/Stevens-Elite-Services\/service-category\/building-renovation\/","name":"Building Renovation","slug":"building-renovation","taxonomy":"service-category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/topbrandingaltimeter.com\/Stevens-Elite-Services\/wp-json\/wp\/v2\/service-category\/42","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/topbrandingaltimeter.com\/Stevens-Elite-Services\/wp-json\/wp\/v2\/service-category"}],"about":[{"href":"https:\/\/topbrandingaltimeter.com\/Stevens-Elite-Services\/wp-json\/wp\/v2\/taxonomies\/service-category"}]}}